{"id":45,"date":"2020-07-26T08:38:27","date_gmt":"2020-07-26T08:38:27","guid":{"rendered":"https:\/\/demo.cmssuperheroes.com\/themeforest\/kindori\/?page_id=45"},"modified":"2026-03-26T21:11:31","modified_gmt":"2026-03-27T02:11:31","slug":"home-1","status":"publish","type":"page","link":"https:\/\/mikiddo.com.co\/","title":{"rendered":"Home 1"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"45\" class=\"elementor elementor-45\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-06481c4 elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-items-top elementor-section-height-default\" data-id=\"06481c4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1fe0d6\" data-id=\"c1fe0d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-811492b elementor-section-full_width elementor-section-content-top elementor-section-height-default elementor-section-height-default\" data-id=\"811492b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-21ccc75\" data-id=\"21ccc75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c76d6e elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"7c76d6e\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-birth.png\" class=\"attachment-large size-large wp-image-2389\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-099e703\" data-id=\"099e703\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69d9ebc animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"69d9ebc\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;shake&quot;,&quot;_animation_delay&quot;:200,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.5,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-clound.png\" class=\"attachment-author-avatar size-author-avatar wp-image-2398\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-c67ed09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c67ed09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-16f9d33\" data-id=\"16f9d33\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb8ae31 elementor-widget elementor-widget-image\" data-id=\"eb8ae31\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"282\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/logo-1024x451.png\" class=\"attachment-large size-large wp-image-4939\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/logo-1024x451.png 1024w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/logo-300x132.png 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/logo-768x338.png 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/logo-1536x676.png 1536w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/logo-2048x902.png 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55fb4df elementor-widget elementor-widget-spacer\" data-id=\"55fb4df\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31f4e6f elementor-widget elementor-widget-heading\" data-id=\"31f4e6f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Centro Educativo Infantil Kiddo <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e19e644 elementor-widget elementor-widget-spacer\" data-id=\"e19e644\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8a2682 elementor-widget elementor-widget-heading\" data-id=\"d8a2682\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a1Donde el aprendizaje es una aventura!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6212404 elementor-widget elementor-widget-spacer\" data-id=\"6212404\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09356f3 elementor-widget elementor-widget-heading\" data-id=\"09356f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00a1Bienvenidos a nuestro colegio, donde la magia y la aventura nunca terminan! <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cde19c elementor-widget elementor-widget-spacer\" data-id=\"0cde19c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c10b30 elementor-widget elementor-widget-button\" data-id=\"4c10b30\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Descrube M\u00e1s<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c7e8322\" data-id=\"c7e8322\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e993fd2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e993fd2\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68ff083\" data-id=\"68ff083\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af15265 elementor-widget elementor-widget-heading\" data-id=\"af15265\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor que elegirnos?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7374e56 elementor-widget elementor-widget-spacer\" data-id=\"7374e56\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4354cf elementor-widget elementor-widget-heading\" data-id=\"a4354cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros valores fundamentales.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82d3e6a elementor-widget elementor-widget-spacer\" data-id=\"82d3e6a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6dc0829 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dc0829\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-713cb73\" data-id=\"713cb73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-05d4403\" data-id=\"05d4403\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d2e44d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1d2e44d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Porque le apostamos por una educaci\u00f3n basada en la ciencia, que comprende c\u00f3mo aprende el cerebro infantil y c\u00f3mo las emociones, el entorno y las experiencias influyen directamente en el desarrollo integral de los ni\u00f1os.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-430cd4b\" data-id=\"430cd4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-da50a90 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"da50a90\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;_animation&quot;:&quot;tada&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-bee.png\" class=\"attachment-large size-large wp-image-849\" alt=\"Kindori\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a06a7a elementor-widget elementor-widget-spacer\" data-id=\"4a06a7a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29acb77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29acb77\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-647f120\" data-id=\"647f120\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b92800 elementor-flip-box--effect-fade e-transform elementor-widget elementor-widget-flip-box\" data-id=\"4b92800\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-20,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-flip-box.min.css\">\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/cuadrados-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4566\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/cuadrados-1-150x150.jpg 150w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/cuadrados-1-300x300.jpg 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/cuadrados-1-768x768.jpg 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/cuadrados-1-160x160.jpg 160w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/cuadrados-1-70x70.jpg 70w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/cuadrados-1.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tModelo Neuroeducativo\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tAprendizaje a trav\u00e9s de la experiencia directa, nuestras estrategias pedag\u00f3gicas est\u00e1n dise\u00f1adas para incorporar la l\u00fadica en la ense\u00f1anza, con el fin de lograr un aprendizaje m\u00e1s atractivo y efectivo.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7fad9ca\" data-id=\"7fad9ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-468444e elementor-flip-box--effect-fade e-transform elementor-widget elementor-widget-flip-box\" data-id=\"468444e\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-20,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4828\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-2-150x150.jpg 150w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-2-300x300.jpg 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-2-768x768.jpg 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-2-160x160.jpg 160w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-2-70x70.jpg 70w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-2.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tBienestar Emocional y Social\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tPara nosotros es fundamental el respeto por las emociones, la empat\u00eda, la comunicaci\u00f3n, la resoluci\u00f3n de conflictos y las interacciones positivas.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-86d5e77\" data-id=\"86d5e77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe25ba7 elementor-flip-box--effect-fade e-transform elementor-widget elementor-widget-flip-box\" data-id=\"fe25ba7\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-20,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4827\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-3-150x150.jpg 150w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-3-300x300.jpg 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-3-768x768.jpg 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-3-160x160.jpg 160w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-3-70x70.jpg 70w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-3.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tEducamos en Verde\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tLos ni\u00f1os peque\u00f1os tienen ritmos biol\u00f3gicos que influyen en su estado de alerta y capacidad de aprendizaje, raz\u00f3n por la cual respetamos estos ritmos, proporcionando tiempos adecuados para el descanso, la alimentaci\u00f3n y la actividad f\u00edsica. \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c07add7\" data-id=\"c07add7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46c062f elementor-flip-box--effect-fade e-transform elementor-widget elementor-widget-flip-box\" data-id=\"46c062f\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-20,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4829\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-4-150x150.jpg 150w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-4-300x300.jpg 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-4-768x768.jpg 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-4-160x160.jpg 160w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-4-70x70.jpg 70w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/cuadrados-4.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tAlimentaci\u00f3n Saludable\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tEn nuestras instalaciones campestres nuestros ni\u00f1os logran interactuar con la naturaleza, fomentar la curiosidad e imaginaci\u00f3n, reducen del estr\u00e9s y fortalecen su salud f\u00edsica. \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3813657 elementor-widget elementor-widget-spacer\" data-id=\"3813657\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8b222de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b222de\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d07d31\" data-id=\"3d07d31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a93d723 elementor-widget elementor-widget-heading\" data-id=\"a93d723\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres que tu hijo estudie en Kiddo?<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63edd5e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"63edd5e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Lleva a tu hijo a Kiddo para que pueda\ndesarrollarse integralmente.\n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7364f97\" data-id=\"7364f97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0014fe elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e0014fe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdUqv0rGop53IIrD6YgwQ_uTjcc7I6Lz-jVaMf3E7iI6Ure0A\/viewform?usp=pp_url\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Inscr\u00edbelo Ahora!<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8ac008 elementor-section-stretched elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8ac008\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4720d02\" data-id=\"4720d02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b744c39 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"b744c39\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;motion_fx_tilt_effect&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;headShake&quot;,&quot;_animation_delay&quot;:100,&quot;motion_fx_tilt_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"616\" height=\"660\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/image-left-home_1.png\" class=\"attachment-large size-large wp-image-4953\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/image-left-home_1.png 616w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/09\/image-left-home_1-280x300.png 280w\" sizes=\"(max-width: 616px) 100vw, 616px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b68ff25\" data-id=\"b68ff25\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60329f2 elementor-widget elementor-widget-heading\" data-id=\"60329f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Acompa\u00f1amos nuevas generaciones hacia el \u00e9xito.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d31b438 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d31b438\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c2f63f elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9c2f63f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\nKiddo propone un modelo pedag\u00f3gico basado en la neuroeducaci\u00f3n el cual consiste en la uni\u00f3n de la educaci\u00f3n y la neurociencia con el objetivo de desarrollar estrategias para estimular el cerebro para un mejor aprendizaje. Este modelo se enfoca en la estimulaci\u00f3n del cerebro y la adaptaci\u00f3n a los diferentes ritmos y estilos de aprendizaje de nuestros ni\u00f1os, proponiendo estrategias innovadoras para los procesos de ense\u00f1anza-aprendizaje en la pr\u00e1ctica pedag\u00f3gica.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fedbab elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4fedbab\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-805af7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"805af7e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0995737\" data-id=\"0995737\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c331c6 elementor-widget elementor-widget-heading\" data-id=\"8c331c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Nuestra Historia<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f391524 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f391524\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f3910f elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8f3910f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">El CENTRO EDUCATIVO INFANTIL KIDDO fue fundado en el a\u00f1o 2019 en la ciudad de Sogamoso, Boyac\u00e1. Su creadora, la licenciada Angelica Maria Sisa Medina, una educadora apasionada por el desarrollo infantil, so\u00f1aba con establecer un centro educativo que proporcionara un entorno seguro y enriquecedor para los ni\u00f1os en edad preescolar.<br>\n<br>Desde sus inicios KIDDO se centr\u00f3 en integrar los  conocimientos de  la neurociencia, la psicolog\u00eda y la  educaci\u00f3n comprendiendo  c\u00f3mo se desarrolla el cerebro y c\u00f3mo se puede optimizar el aprendizaje y el desarrollo en las diferentes etapas del preescolar.<br> <br>Hemos dise\u00f1ado un  curr\u00edculo el cual a trav\u00e9s de actividades l\u00fadicas, el juego simb\u00f3lico y la interacci\u00f3n social pretende fomentar un aprendizaje significativo y vivencial.  <br>\n<br>Durante estos a\u00f1os, KIDDO ha ganado reconocimiento local por su modelo pedag\u00f3gico innovador, su aprendizaje personalizado, apoyo emocional y su ambiente campestre. \n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d2f573a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d2f573a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25c1041\" data-id=\"25c1041\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30ec0b3 elementor-widget elementor-widget-spacer\" data-id=\"30ec0b3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e14939 elementor-widget elementor-widget-spacer\" data-id=\"2e14939\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3300f06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3300f06\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2ad8b2c\" data-id=\"2ad8b2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-078985e animated-slow e-transform e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"078985e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;pulse&quot;,&quot;_animation_delay&quot;:100,&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-home-2.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2020\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-779fead\" data-id=\"779fead\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c06a0 elementor-widget elementor-widget-heading\" data-id=\"98c06a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pensamos en los ni\u00f1os<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c212549 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c212549\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1cfb27 elementor-widget elementor-widget-heading\" data-id=\"e1cfb27\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Actividades Para Los Ni\u00f1os<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e86d87 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8e86d87\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-789d69d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"789d69d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">El aula infantil ofrece estrategias para construir relaciones positivas, ayudar a los ni\u00f1os a desarrollar la autorregulaci\u00f3n y responder a conductas desafiantes.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8e89c50\" data-id=\"8e89c50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f4366e animated-slow e-transform e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1f4366e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;pulse&quot;,&quot;_animation_delay&quot;:100,&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-100,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-home-3.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2024\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-11e9a8d animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"11e9a8d\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;_animation&quot;:&quot;tada&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-bee.png\" class=\"attachment-large size-large wp-image-849\" alt=\"Kindori\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-4522805 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4522805\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-367b21f\" data-id=\"367b21f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3edaef2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3edaef2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8029667 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8029667\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4036b86 elementor-widget elementor-widget-heading\" data-id=\"4036b86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Individualizaci\u00f3n y Adaptaci\u00f3n<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8a3e10 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c8a3e10\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d256ef4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d256ef4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cada ni\u00f1o es \u00fanico y tiene un ritmo de desarrollo diferente. Nos destacamos por ser lo suficientemente flexibles adapt\u00e1ndonos a las necesidades individuales<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63461d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"63461d7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8869f2a\" data-id=\"8869f2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b856c92 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b856c92\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7b4d6 elementor-widget elementor-widget-image\" data-id=\"dd7b4d6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/child-man.png\" class=\"attachment-large size-large wp-image-2029\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca7aba7\" data-id=\"ca7aba7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44269f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"44269f7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-869b681 elementor-widget elementor-widget-heading\" data-id=\"869b681\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Actividades Al Aire Libre<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61d91d4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"61d91d4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391c5fb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"391c5fb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">En nuestras instalaciones campestres nuestros ni\u00f1os logran interactuar con la naturaleza, fomentar la curiosidad e imaginaci\u00f3n.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391792c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"391792c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82f9470 elementor-widget elementor-widget-heading\" data-id=\"82f9470\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Actividades Culturales<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e60492b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e60492b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6069b2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f6069b2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Las actividades creativas ayudan a los ni\u00f1os a desarrollar una inteligencia integral.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b06c6f elementor-widget elementor-widget-spacer\" data-id=\"1b06c6f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6516ee7 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6516ee7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9dca640 cms-bg-secondary\" data-id=\"9dca640\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-db92e98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db92e98\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f18b045\" data-id=\"f18b045\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac51270 elementor-widget elementor-widget-heading\" data-id=\"ac51270\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros Programas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a7923c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5a7923c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da4cb7a elementor-widget elementor-widget-heading\" data-id=\"da4cb7a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Un nivel para cada momento<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1be6af0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1be6af0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1cf466 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f1cf466\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Centro Educativo Infantil Kiddo cuenta con la aprobaci\u00f3n para los siguientes programas para la educaci\u00f3n de tus hijos.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6cd9cc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c6cd9cc\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f8f25 elementor-widget elementor-widget-accordion\" data-id=\"18f8f25\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2611\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">PARVULITOS  15 a 24 meses<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2611\"><p>Durante etapa el cerebro del ni\u00f1o es extremadamente pl\u00e1stico, lo que significa que est\u00e1 en un estado de constante cambio y adaptaci\u00f3n. Las experiencias que el ni\u00f1o vive durante este tiempo pueden tener un impacto significativo en la formaci\u00f3n de redes neuronales y en el desarrollo de habilidades cognitivas y emocionales.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2612\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2612\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">PARVULOS  2 a\u00f1os <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2612\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2612\"><p>A los 2 a\u00f1os, el cerebro de los ni\u00f1os est\u00e1 en una fase de alta plasticidad, lo que significa que es extremadamente receptivo a las experiencias. Las conexiones sin\u00e1pticas se est\u00e1n formando r\u00e1pidamente, y las experiencias sensoriales, motoras y emocionales tienen un impacto significativo en la configuraci\u00f3n de las redes neuronales. Kiddo enfatiza en\u00a0 la importancia de proporcionar un entorno rico y estimulante que fomente la exploraci\u00f3n y el aprendizaje.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2613\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2613\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">PRE JARDIN 3 a\u00f1os<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2613\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2613\"><p>A los 3 a\u00f1os, el cerebro de los ni\u00f1os sigue siendo extremadamente pl\u00e1stico, lo que significa que es muy adaptable y capaz de formar nuevas conexiones en respuesta a las experiencias. Este es un momento crucial para el aprendizaje, ya que las experiencias tempranas tienen un impacto significativo en la arquitectura cerebral. Kiddo destaca la importancia de proporcionar un ambiente enriquecido y variado que promueva la exploraci\u00f3n y el descubrimiento.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2614\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2614\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">JARDIN 4 a\u00f1os<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2614\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2614\"><p>A los 4 a\u00f1os, los ni\u00f1os muestran un aumento significativo en su capacidad para procesar informaci\u00f3n y resolver problemas. La neuroeducaci\u00f3n destaca c\u00f3mo las experiencias de aprendizaje en esta etapa pueden fortalecer las conexiones neuronales, facilitando habilidades como la memoria, la atenci\u00f3n y el razonamiento l\u00f3gico. Kiddo sugiere que proporcionar experiencias de aprendizaje activas y variadas, como juegos educativos, actividades manipulativas y resoluci\u00f3n de problemas, apoya el desarrollo de nuevas conexiones neuronales y refuerza el aprendizaje.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2615\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2615\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-times-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm121.6 313.1c4.7 4.7 4.7 12.3 0 17L338 377.6c-4.7 4.7-12.3 4.7-17 0L256 312l-65.1 65.6c-4.7 4.7-12.3 4.7-17 0L134.4 338c-4.7-4.7-4.7-12.3 0-17l65.6-65-65.6-65.1c-4.7-4.7-4.7-12.3 0-17l39.6-39.6c4.7-4.7 12.3-4.7 17 0l65 65.7 65.1-65.6c4.7-4.7 12.3-4.7 17 0l39.6 39.6c4.7 4.7 4.7 12.3 0 17L312 256l65.6 65.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">TRANSICION 5 a\u00f1os<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2615\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2615\"><p>A los 5 a\u00f1os, los ni\u00f1os comienzan a desarrollar habilidades para el pensamiento abstracto, la resoluci\u00f3n de problemas m\u00e1s complejos y la planificaci\u00f3n. Kiddo resalta la importancia de proporcionar experiencias que desaf\u00eden a los ni\u00f1os a pensar cr\u00edticamente y a resolver problemas, ya que esto estimula la formaci\u00f3n y fortalecimiento de conexiones neuronales en \u00e1reas del cerebro relacionadas con el razonamiento y la toma de decisiones.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48a8d1f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"48a8d1f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b8d9e40\" data-id=\"b8d9e40\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6893e0 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f6893e0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f5f77a\" data-id=\"9f5f77a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-b410ac4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b410ac4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f78eae6\" data-id=\"f78eae6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0b4fe1f\" data-id=\"0b4fe1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2047a7f elementor-widget elementor-widget-heading\" data-id=\"2047a7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aprender Jugando<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-442c7da elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"442c7da\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a985a8 elementor-widget elementor-widget-heading\" data-id=\"1a985a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestras Clases<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-549b591 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"549b591\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-351c04c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"351c04c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">El aula infantil ofrece estrategias para construir relaciones positivas, ayudar a los ni\u00f1os a desarrollar la autorregulaci\u00f3n y responder a conductas desafiantes.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebb6459 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ebb6459\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c44750 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9c44750\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0116a5e elementor-widget elementor-widget-image\" data-id=\"0116a5e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-bee.png\" class=\"attachment-large size-large wp-image-849\" alt=\"Kindori\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f6fac8d\" data-id=\"f6fac8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e076ca3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e076ca3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2744570 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2744570\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5b58054e\" data-id=\"5b58054e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35625b8 elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"35625b8\" data-element_type=\"widget\" data-settings=\"{&quot;template_id&quot;:4648,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-widget-container&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-loop-builder.min.css\">\t\t<div class=\"swiper elementor-loop-container elementor-grid\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t<style id=\"loop-4648\">.elementor-4648 .elementor-element.elementor-element-3f25c9e{--display:flex;--background-transition:0.3s;}.elementor-4648 .elementor-element.elementor-element-7d2a136{text-align:center;}.elementor-4648 .elementor-element.elementor-element-7d2a136 .elementor-heading-title{color:#1D1E20;font-family:\"Fredoka\", Sans-serif;font-weight:500;}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4648\" class=\"elementor elementor-4648 swiper-slide e-loop-item e-loop-item-4665 post-4665 post type-post status-publish format-standard has-post-thumbnail hentry category-clases\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-3f25c9e e-flex e-con-boxed e-con e-parent\" data-id=\"3f25c9e\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa7931 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"6aa7931\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-03-300x200.jpg\" class=\"attachment-medium size-medium wp-image-4902\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-03-300x200.jpg 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-03-1024x683.jpg 1024w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-03-768x512.jpg 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-03.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2a136 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"7d2a136\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Explorando Talentos<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4648\" class=\"elementor elementor-4648 swiper-slide e-loop-item e-loop-item-4663 post-4663 post type-post status-publish format-standard has-post-thumbnail hentry category-clases\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-3f25c9e e-flex e-con-boxed e-con e-parent\" data-id=\"3f25c9e\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa7931 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"6aa7931\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-02-300x200.jpg\" class=\"attachment-medium size-medium wp-image-4904\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-02-300x200.jpg 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-02-1024x683.jpg 1024w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-02-768x512.jpg 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-02.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2a136 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"7d2a136\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">M\u00fasica Para La Imaginaci\u00f3n<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4648\" class=\"elementor elementor-4648 swiper-slide e-loop-item e-loop-item-4660 post-4660 post type-post status-publish format-standard has-post-thumbnail hentry category-clases\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-3f25c9e e-flex e-con-boxed e-con e-parent\" data-id=\"3f25c9e\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa7931 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"6aa7931\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-01-300x200.jpg\" class=\"attachment-medium size-medium wp-image-4905\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-01-300x200.jpg 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-01-1024x683.jpg 1024w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-01-768x512.jpg 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/06\/classes-01.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2a136 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"7d2a136\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Aprendiendo Disciplina<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-455f9d7d elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"455f9d7d\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f04bbbf\" data-id=\"7f04bbbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-2840dc6 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2840dc6\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd57ac2\" data-id=\"bd57ac2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-6e35366a elementor-section-stretched bg-four elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e35366a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6d9ad168\" data-id=\"6d9ad168\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c45e756 e-flex e-con-boxed e-con e-parent\" data-id=\"c45e756\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1416f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6c1416f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chalkboard-teacher\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M208 352c-2.39 0-4.78.35-7.06 1.09C187.98 357.3 174.35 360 160 360c-14.35 0-27.98-2.7-40.95-6.91-2.28-.74-4.66-1.09-7.05-1.09C49.94 352-.33 402.48 0 464.62.14 490.88 21.73 512 48 512h224c26.27 0 47.86-21.12 48-47.38.33-62.14-49.94-112.62-112-112.62zm-48-32c53.02 0 96-42.98 96-96s-42.98-96-96-96-96 42.98-96 96 42.98 96 96 96zM592 0H208c-26.47 0-48 22.25-48 49.59V96c23.42 0 45.1 6.78 64 17.8V64h352v288h-64v-64H384v64h-76.24c19.1 16.69 33.12 38.73 39.69 64H592c26.47 0 48-22.25 48-49.59V49.59C640 22.25 618.47 0 592 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed5ca6 elementor-widget elementor-widget-counter\" data-id=\"9ed5ca6\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-counter .elementor-counter-number-wrapper{display:flex;font-size:69px;font-weight:600;line-height:1}.elementor-counter .elementor-counter-number-prefix,.elementor-counter .elementor-counter-number-suffix{flex-grow:1;white-space:pre-wrap}.elementor-counter .elementor-counter-number-prefix{text-align:right}.elementor-counter .elementor-counter-number-suffix{text-align:left}.elementor-counter .elementor-counter-title{text-align:center;font-size:19px;font-weight:400;line-height:2.5}<\/style>\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"10\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-counter-title\">Profesores<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d5a379e\" data-id=\"d5a379e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8b8f58a\" data-id=\"8b8f58a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-859f608 e-flex e-con-boxed e-con e-parent\" data-id=\"859f608\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-985cad2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"985cad2\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book-reader\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M352 96c0-53.02-42.98-96-96-96s-96 42.98-96 96 42.98 96 96 96 96-42.98 96-96zM233.59 241.1c-59.33-36.32-155.43-46.3-203.79-49.05C13.55 191.13 0 203.51 0 219.14v222.8c0 14.33 11.59 26.28 26.49 27.05 43.66 2.29 131.99 10.68 193.04 41.43 9.37 4.72 20.48-1.71 20.48-11.87V252.56c-.01-4.67-2.32-8.95-6.42-11.46zm248.61-49.05c-48.35 2.74-144.46 12.73-203.78 49.05-4.1 2.51-6.41 6.96-6.41 11.63v245.79c0 10.19 11.14 16.63 20.54 11.9 61.04-30.72 149.32-39.11 192.97-41.4 14.9-.78 26.49-12.73 26.49-27.06V219.14c-.01-15.63-13.56-28.01-29.81-27.09z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48e6c2a elementor-widget elementor-widget-counter\" data-id=\"48e6c2a\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-counter-title\">Estudiantes<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a1f9b28\" data-id=\"a1f9b28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5cb99f39\" data-id=\"5cb99f39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32ccf14 e-flex e-con-boxed e-con e-parent\" data-id=\"32ccf14\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14b8370 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"14b8370\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-sun\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 160c-52.9 0-96 43.1-96 96s43.1 96 96 96 96-43.1 96-96-43.1-96-96-96zm246.4 80.5l-94.7-47.3 33.5-100.4c4.5-13.6-8.4-26.5-21.9-21.9l-100.4 33.5-47.4-94.8c-6.4-12.8-24.6-12.8-31 0l-47.3 94.7L92.7 70.8c-13.6-4.5-26.5 8.4-21.9 21.9l33.5 100.4-94.7 47.4c-12.8 6.4-12.8 24.6 0 31l94.7 47.3-33.5 100.5c-4.5 13.6 8.4 26.5 21.9 21.9l100.4-33.5 47.3 94.7c6.4 12.8 24.6 12.8 31 0l47.3-94.7 100.4 33.5c13.6 4.5 26.5-8.4 21.9-21.9l-33.5-100.4 94.7-47.3c13-6.5 13-24.7.2-31.1zm-155.9 106c-49.9 49.9-131.1 49.9-181 0-49.9-49.9-49.9-131.1 0-181 49.9-49.9 131.1-49.9 181 0 49.9 49.9 49.9 131.1 0 181z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a08ccb0 elementor-widget elementor-widget-counter\" data-id=\"a08ccb0\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"2019\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-counter-title\">Desde<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1eef74 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1eef74\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72c7507\" data-id=\"72c7507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5ffce0 elementor-widget elementor-widget-heading\" data-id=\"a5ffce0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acerca De Los Profesores<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352e65c elementor-widget elementor-widget-spacer\" data-id=\"352e65c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c72ca elementor-widget elementor-widget-heading\" data-id=\"c5c72ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros Profesores<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5094814 elementor-widget elementor-widget-spacer\" data-id=\"5094814\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c50ddd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c50ddd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0882e04\" data-id=\"0882e04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-aca177b\" data-id=\"aca177b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a432360 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"a432360\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contamos con un excelente equipo de trabajo para garantizar que cada ni\u00f1o tenga la atenci\u00f3n y el cuidado necesarios.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e0812ca\" data-id=\"e0812ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0de231e animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0de231e\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;_animation&quot;:&quot;tada&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2020\/08\/image-bee.png\" class=\"attachment-large size-large wp-image-849\" alt=\"Kindori\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e1e6a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e1e6a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-9e70e97\" data-id=\"9e70e97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-0756af5\" data-id=\"0756af5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f945599 elementor-flip-box--effect-slide e-transform elementor-flip-box--direction-right elementor-widget elementor-widget-flip-box\" data-id=\"f945599\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect_hover&quot;:&quot;transform&quot;}\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/directora-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-5024\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/directora-150x150.png 150w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/directora-300x300.png 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/directora-768x768.png 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/directora-160x160.png 160w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/directora-70x70.png 70w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/directora.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tANGELICA MARIA SISA MEDINA\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tRectora\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-c2299aa\" data-id=\"c2299aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32c8272 elementor-flip-box--effect-slide e-transform elementor-flip-box--direction-right elementor-widget elementor-widget-flip-box\" data-id=\"32c8272\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect_hover&quot;:&quot;transform&quot;}\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/ParvulosB-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-5026\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/ParvulosB-150x150.png 150w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/ParvulosB-300x300.png 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/ParvulosB-768x768.png 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/ParvulosB-160x160.png 160w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/ParvulosB-70x70.png 70w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/ParvulosB.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tLEIDY NATALIA M\u00c9NDEZ VELOZA\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\t\nP\u00e1rvulos B\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-1716a39\" data-id=\"1716a39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd17382 elementor-flip-box--effect-slide e-transform elementor-flip-box--direction-right elementor-widget elementor-widget-flip-box\" data-id=\"fd17382\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect_hover&quot;:&quot;transform&quot;}\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/Prejardin-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-5027\" alt=\"\" srcset=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/Prejardin-150x150.png 150w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/Prejardin-300x300.png 300w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/Prejardin-768x768.png 768w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/Prejardin-160x160.png 160w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/Prejardin-70x70.png 70w, https:\/\/mikiddo.com.co\/wp-content\/uploads\/2025\/04\/Prejardin.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tALBA JANETH RODR\u00cdGUEZ SAAVEDRA\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\t\nPrejard\u00edn\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-8b42d65\" data-id=\"8b42d65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-39d8f1a elementor-widget elementor-widget-spacer\" data-id=\"39d8f1a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e2cd96 elementor-widget elementor-widget-spacer\" data-id=\"8e2cd96\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e26c61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e26c61\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7b0d2ff\" data-id=\"7b0d2ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46add74 elementor-widget elementor-widget-heading\" data-id=\"46add74\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres que tu hijo estudie en Kiddo?<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69f1c2a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"69f1c2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Lleva a tu hijo a Kiddo para que pueda\ndesarrollarse integralmente.\n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-296c040\" data-id=\"296c040\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b9d3cf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3b9d3cf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdUqv0rGop53IIrD6YgwQ_uTjcc7I6Lz-jVaMf3E7iI6Ure0A\/viewform?usp=pp_url\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Inscr\u00edbelo Ahora!<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6adbd81 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6adbd81\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5852fa5\" data-id=\"5852fa5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb4a876 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb4a876\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:26,&quot;end&quot;:79}},&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f499150\" data-id=\"f499150\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0707a47 elementor-widget elementor-widget-heading\" data-id=\"0707a47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">19 de enero, 2026 a las 08:00 AM<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b47b7fd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b47b7fd\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12e9a8d elementor-widget elementor-widget-heading\" data-id=\"12e9a8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a1Inicia nuestra gran aventura 2026!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8770907 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8770907\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9565bda elementor-countdown--label-block elementor-widget elementor-widget-countdown\" data-id=\"9565bda\" data-element_type=\"widget\" data-widget_type=\"countdown.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.20.0 - 11-03-2024 *\/\n.elementor-widget-countdown .elementor-countdown-expire--message{display:none;padding:20px;text-align:center}.elementor-widget-countdown .elementor-countdown-wrapper{flex-direction:row}.elementor-widget-countdown .elementor-countdown-item{padding:20px 0;text-align:center;color:#fff}.elementor-widget-countdown .elementor-countdown-digits,.elementor-widget-countdown .elementor-countdown-label{line-height:1}.elementor-widget-countdown .elementor-countdown-digits{font-size:69px}.elementor-widget-countdown .elementor-countdown-label{font-size:19px}.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-wrapper{display:flex;justify-content:center;margin-right:auto;margin-left:auto}.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-digits,.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-label{display:block}.elementor-widget-countdown.elementor-countdown--label-block .elementor-countdown-item{flex-basis:0;flex-grow:1}.elementor-widget-countdown.elementor-countdown--label-inline{text-align:center}.elementor-widget-countdown.elementor-countdown--label-inline .elementor-countdown-item{display:inline-block;padding-left:5px;padding-right:5px}<\/style>\t\t<div data-expire-actions=\"[{&quot;type&quot;:&quot;message&quot;}]\" class=\"elementor-countdown-wrapper\" data-date=\"1768827600\">\n\t\t\t<div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-days\"><\/span> <span class=\"elementor-countdown-label\">D\u00edas<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-hours\"><\/span> <span class=\"elementor-countdown-label\">Horas<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-minutes\"><\/span> <span class=\"elementor-countdown-label\">Minutos<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-seconds\"><\/span> <span class=\"elementor-countdown-label\">Segundos<\/span><\/div>\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-countdown-expire--message\">\n\t\t\t\t\tLets go!\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c802514 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c802514\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0970079\" data-id=\"0970079\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e1648c elementor-widget elementor-widget-heading\" data-id=\"3e1648c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descubre nuestra imagen<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3e0f19 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e3e0f19\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-388a57c elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"388a57c\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-carousel.min.css\">\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"bg-page-title-about-2\" style=\"background-image: url(&#039;https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/bg-page-title-about-2.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"bg-page-title-about-1\" style=\"background-image: url(&#039;https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/bg-page-title-about-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"bg-page-title-about-3\" style=\"background-image: url(&#039;https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/bg-page-title-about-3.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"bg-page-title-about-4\" style=\"background-image: url(&#039;https:\/\/mikiddo.com.co\/wp-content\/uploads\/2024\/08\/bg-page-title-about-4.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47a15647 elementor-section-stretched bg-four elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47a15647\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d3bf56e\" data-id=\"5d3bf56e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1ccd2a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ccd2a6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9556ef5\" data-id=\"9556ef5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-299baf4 elementor-widget elementor-widget-heading\" data-id=\"299baf4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres que tu hijo estudie en Kiddo?<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d6229c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5d6229c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Lleva a tu hijo a Kiddo para que pueda\ndesarrollarse integralmente.\n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1618dac\" data-id=\"1618dac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b910b3e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b910b3e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdUqv0rGop53IIrD6YgwQ_uTjcc7I6Lz-jVaMf3E7iI6Ure0A\/viewform?usp=pp_url\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1Inscr\u00edbelo Ahora!<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e779b69 e-flex e-con-boxed e-con e-parent\" data-id=\"e779b69\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d6569f9 e-con-full e-flex e-con e-child\" data-id=\"d6569f9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5812813 elementor-grid-1 elementor-shape-rounded e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"5812813\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em));height:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-threads{background-color:#000}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-x-twitter{background-color:#000}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-c73221c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1ee600 elementor-widget elementor-widget-facebook-page\" data-id=\"e1ee600\" data-element_type=\"widget\" data-widget_type=\"facebook-page.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.20.0 - 11-03-2024 *\/\n.elementor-facebook-widget.fb_iframe_widget,.elementor-facebook-widget.fb_iframe_widget span{width:100%!important}.elementor-facebook-widget.fb_iframe_widget iframe{position:relative;width:100%!important}.elementor-facebook-widget.fb-like{height:1px}.elementor-widget-facebook-comments iframe{width:100%!important}<\/style><div class=\"elementor-facebook-widget fb-page\" data-href=\"https:\/\/www.facebook.com\/mikiddo.co\" data-tabs=\"timeline\" data-height=\"428px\" data-width=\"500px\" data-small-header=\"true\" data-hide-cover=\"true\" data-show-facepile=\"false\" data-hide-cta=\"true\" style=\"min-height: 1px;height:428px\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd32939 e-con-full e-flex e-con e-child\" data-id=\"fd32939\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e518658 elementor-widget elementor-widget-google_maps\" data-id=\"e518658\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyCueTT9_h3aeK678ZJylkfo9R-KzEYHc3M&#038;q=Kiddo%20Sogamoso&#038;zoom=14\"\n\t\t\t\t\ttitle=\"Kiddo Sogamoso\"\n\t\t\t\t\taria-label=\"Kiddo Sogamoso\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d95dede e-con-full e-flex e-con e-child\" data-id=\"d95dede\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9ef8ab elementor-grid-1 elementor-shape-rounded e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"e9ef8ab\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-c73221c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a8f86 elementor-widget elementor-widget-shortcode\" data-id=\"45a8f86\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"sb_instagram_header  sbi_header_outside\"   >\n\t<a class=\"sbi_header_link\" target=\"_blank\" rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/mikiddo.com.co\/\" title=\"@mikiddo.com.co\">\n\t\t<div class=\"sbi_header_text\">\n\t\t\t<div class=\"sbi_header_img\"  data-avatar-url=\"https:\/\/scontent-lga3-2.cdninstagram.com\/v\/t51.2885-19\/336515712_526407376110080_877715316612257288_n.jpg?stp=dst-jpg_s206x206_tt6&amp;_nc_cat=109&amp;ccb=7-5&amp;_nc_sid=bf7eb4&amp;efg=eyJ2ZW5jb2RlX3RhZyI6InByb2ZpbGVfcGljLnd3dy4xMDgwLkMzIn0%3D&amp;_nc_ohc=JPUcvD7d6wEQ7kNvwFuwZyP&amp;_nc_oc=AdmHOD3bMVHkdiKDlrFHSsXYTQ2YuZFHdiKM6XQ1nmwHk3U8djWWRrYY0x5RIre1s-JD6wVvOPSGJTQeO22TiFUv&amp;_nc_zt=24&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=AP4hL3IEAAAA&amp;_nc_tpa=Q5bMBQHbR0BKshFl9lv3cgO5nO0far_ou15fB2X7VIwA-6VZ53K3G1khhcZhhqZuBDOZk4PiKdd33HPTlw&amp;oh=00_AfoAHqY-ejsQkv4VEzOL-lJJiptiXcKEgIqxWtKasfFdGw&amp;oe=69684AB8\">\n\t\t\t\t\t\t\t\t\t<div class=\"sbi_header_img_hover\"  ><svg class=\"sbi_new_logo fa-instagram fa-w-14\" aria-hidden=\"true\" data-fa-processed=\"\" aria-label=\"Instagram\" data-prefix=\"fab\" data-icon=\"instagram\" role=\"img\" viewBox=\"0 0 448 512\">\n\t                <path fill=\"currentColor\" d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path>\n\t            <\/svg><\/div>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/mikiddo.com.co\/wp-content\/uploads\/sb-instagram-feed-images\/mikiddo.com.co.webp\" alt=\"Centro Educativo Infantil Kiddo\" width=\"50\" height=\"50\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"sbi_feedtheme_header_text\">\n\t\t\t\t<h3>mikiddo.com.co<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"sbi_bio\">\ud83c\udf08<br>\nAprendizaje significativo por medio del juego.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\n<div id=\"sb_instagram\"  class=\"sbi sbi_mob_col_1 sbi_tab_col_1 sbi_col_3 sbi_width_resp sbi_fixed_height\" style=\"padding-bottom: 10px;height: 325px;\" data-feedid=\"*1\"  data-res=\"auto\" data-cols=\"3\" data-colsmobile=\"1\" data-colstablet=\"1\" data-num=\"9\" data-nummobile=\"1\" data-item-padding=\"5\" data-shortcode-atts=\"{&quot;feed&quot;:&quot;1&quot;}\"  data-postid=\"4660\" data-locatornonce=\"785f321b0d\" data-imageaspectratio=\"1:1\" data-sbi-flags=\"favorLocal\">\n\t\n    <div id=\"sbi_images\"  style=\"gap: 10px;\">\n\t\t<div class=\"sbi_item sbi_type_video sbi_new sbi_transition\" id=\"sbi_18085095811832845\" data-date=\"1764023476\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DRdL9pYiTwe\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-3.cdninstagram.com\/v\/t51.71878-15\/587490330_2421005255002940_8181823124154054745_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=106&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=qxi2Qa3KjaQQ7kNvwG5i7xy&#038;_nc_oc=Adn0X_eC759asewi2wO_OuGFrCEsOCueCxx_FVJkpoOu4fj6zCaNSkIino196OfLXh1lsUMWUcby4zawSLp7jbDT&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-3.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_AfrvJDofdzGEETTnOdPERxAbDBoGdlf0gkuVGqY3g5AsjA&#038;oe=69683179\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/587490330_2421005255002940_8181823124154054745_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qxi2Qa3KjaQQ7kNvwG5i7xy&amp;_nc_oc=Adn0X_eC759asewi2wO_OuGFrCEsOCueCxx_FVJkpoOu4fj6zCaNSkIino196OfLXh1lsUMWUcby4zawSLp7jbDT&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrvJDofdzGEETTnOdPERxAbDBoGdlf0gkuVGqY3g5AsjA&amp;oe=69683179&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/587490330_2421005255002940_8181823124154054745_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qxi2Qa3KjaQQ7kNvwG5i7xy&amp;_nc_oc=Adn0X_eC759asewi2wO_OuGFrCEsOCueCxx_FVJkpoOu4fj6zCaNSkIino196OfLXh1lsUMWUcby4zawSLp7jbDT&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrvJDofdzGEETTnOdPERxAbDBoGdlf0gkuVGqY3g5AsjA&amp;oe=69683179&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/587490330_2421005255002940_8181823124154054745_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qxi2Qa3KjaQQ7kNvwG5i7xy&amp;_nc_oc=Adn0X_eC759asewi2wO_OuGFrCEsOCueCxx_FVJkpoOu4fj6zCaNSkIino196OfLXh1lsUMWUcby4zawSLp7jbDT&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrvJDofdzGEETTnOdPERxAbDBoGdlf0gkuVGqY3g5AsjA&amp;oe=69683179&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/587490330_2421005255002940_8181823124154054745_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qxi2Qa3KjaQQ7kNvwG5i7xy&amp;_nc_oc=Adn0X_eC759asewi2wO_OuGFrCEsOCueCxx_FVJkpoOu4fj6zCaNSkIino196OfLXh1lsUMWUcby4zawSLp7jbDT&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrvJDofdzGEETTnOdPERxAbDBoGdlf0gkuVGqY3g5AsjA&amp;oe=69683179&quot;}\">\n            <span class=\"sbi-screenreader\">Publicaci\u00f3n de Instagram 18085095811832845<\/span>\n            \t        <svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>            <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Publicaci\u00f3n de Instagram 18085095811832845\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_image sbi_new sbi_transition\" id=\"sbi_18076733042324563\" data-date=\"1763045013\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/p\/DRABu-MkVAi\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-3.cdninstagram.com\/v\/t51.82787-15\/581007704_18520884226066659_4907566387772387064_n.webp?stp=dst-jpg_e35_tt6&#038;_nc_cat=104&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=rAYzu4uApqUQ7kNvwFnyVQm&#038;_nc_oc=AdkCgZg6Tf_A5eVEHLksIEYDKnZleVTYT3-iIF8uhzzLsz6-UucskwQVptT2RGR9pxR6jVAQ5AnPfe_JBnIssAV2&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-3.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_AfrK8D6S1VDTTySwLzKUv3R_UywO-kZU1csWmt-FggQwWg&#038;oe=69685236\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/581007704_18520884226066659_4907566387772387064_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=rAYzu4uApqUQ7kNvwFnyVQm&amp;_nc_oc=AdkCgZg6Tf_A5eVEHLksIEYDKnZleVTYT3-iIF8uhzzLsz6-UucskwQVptT2RGR9pxR6jVAQ5AnPfe_JBnIssAV2&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrK8D6S1VDTTySwLzKUv3R_UywO-kZU1csWmt-FggQwWg&amp;oe=69685236&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/581007704_18520884226066659_4907566387772387064_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=rAYzu4uApqUQ7kNvwFnyVQm&amp;_nc_oc=AdkCgZg6Tf_A5eVEHLksIEYDKnZleVTYT3-iIF8uhzzLsz6-UucskwQVptT2RGR9pxR6jVAQ5AnPfe_JBnIssAV2&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrK8D6S1VDTTySwLzKUv3R_UywO-kZU1csWmt-FggQwWg&amp;oe=69685236&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/581007704_18520884226066659_4907566387772387064_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=rAYzu4uApqUQ7kNvwFnyVQm&amp;_nc_oc=AdkCgZg6Tf_A5eVEHLksIEYDKnZleVTYT3-iIF8uhzzLsz6-UucskwQVptT2RGR9pxR6jVAQ5AnPfe_JBnIssAV2&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrK8D6S1VDTTySwLzKUv3R_UywO-kZU1csWmt-FggQwWg&amp;oe=69685236&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/581007704_18520884226066659_4907566387772387064_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=rAYzu4uApqUQ7kNvwFnyVQm&amp;_nc_oc=AdkCgZg6Tf_A5eVEHLksIEYDKnZleVTYT3-iIF8uhzzLsz6-UucskwQVptT2RGR9pxR6jVAQ5AnPfe_JBnIssAV2&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrK8D6S1VDTTySwLzKUv3R_UywO-kZU1csWmt-FggQwWg&amp;oe=69685236&quot;}\">\n            <span class=\"sbi-screenreader\">Publicaci\u00f3n de Instagram 18076733042324563<\/span>\n            \t                    <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Publicaci\u00f3n de Instagram 18076733042324563\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\" id=\"sbi_18313519198216554\" data-date=\"1762973914\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DQ96EkQidrY\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-3.cdninstagram.com\/v\/t51.71878-15\/582236157_1632961561445462_7778157218133196609_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=104&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=HJIp0gCrLUYQ7kNvwHQDmOp&#038;_nc_oc=AdnNgehKMsOn0N-pHkUrPAFZfx_y9Q-qnY82NtyBEFk8B-vHfzBCwYu-C8LzUMgdEVmRZjZeYTHIgwyL9NgsIAO4&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-3.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_Afor3jzwTa31lGwZWcRaqdM6dBcU3mNVjmcfrIByWsP74w&#038;oe=69683B40\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/582236157_1632961561445462_7778157218133196609_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=HJIp0gCrLUYQ7kNvwHQDmOp&amp;_nc_oc=AdnNgehKMsOn0N-pHkUrPAFZfx_y9Q-qnY82NtyBEFk8B-vHfzBCwYu-C8LzUMgdEVmRZjZeYTHIgwyL9NgsIAO4&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afor3jzwTa31lGwZWcRaqdM6dBcU3mNVjmcfrIByWsP74w&amp;oe=69683B40&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/582236157_1632961561445462_7778157218133196609_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=HJIp0gCrLUYQ7kNvwHQDmOp&amp;_nc_oc=AdnNgehKMsOn0N-pHkUrPAFZfx_y9Q-qnY82NtyBEFk8B-vHfzBCwYu-C8LzUMgdEVmRZjZeYTHIgwyL9NgsIAO4&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afor3jzwTa31lGwZWcRaqdM6dBcU3mNVjmcfrIByWsP74w&amp;oe=69683B40&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/582236157_1632961561445462_7778157218133196609_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=HJIp0gCrLUYQ7kNvwHQDmOp&amp;_nc_oc=AdnNgehKMsOn0N-pHkUrPAFZfx_y9Q-qnY82NtyBEFk8B-vHfzBCwYu-C8LzUMgdEVmRZjZeYTHIgwyL9NgsIAO4&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afor3jzwTa31lGwZWcRaqdM6dBcU3mNVjmcfrIByWsP74w&amp;oe=69683B40&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/582236157_1632961561445462_7778157218133196609_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=HJIp0gCrLUYQ7kNvwHQDmOp&amp;_nc_oc=AdnNgehKMsOn0N-pHkUrPAFZfx_y9Q-qnY82NtyBEFk8B-vHfzBCwYu-C8LzUMgdEVmRZjZeYTHIgwyL9NgsIAO4&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afor3jzwTa31lGwZWcRaqdM6dBcU3mNVjmcfrIByWsP74w&amp;oe=69683B40&quot;}\">\n            <span class=\"sbi-screenreader\">Los esperamos\ud83c\udf08\u263a\ufe0f\u2728<\/span>\n            \t        <svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>            <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Los esperamos\ud83c\udf08\u263a\ufe0f\u2728\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_image sbi_new sbi_transition\" id=\"sbi_18106493620624839\" data-date=\"1762545877\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/p\/DQxJtQZifFK\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-2.cdninstagram.com\/v\/t51.82787-15\/575997818_18518579827066659_8671000027546985535_n.webp?stp=dst-jpg_e35_tt6&#038;_nc_cat=100&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=VRyEzeKRkasQ7kNvwHgMjEk&#038;_nc_oc=AdmFLAnwshiD-HhRT7lJ5h8ISbKJxwhdIj4vn5dtUM0QozNsg7I-8ahsu0o6iaJpL_b3wj5ekTA2AoiU3Ds6FKdf&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_AfrBLlZxG3hYz36s0rhW1l_dYVwYz4feiC1is4OhOMjaXg&#038;oe=696833C2\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/575997818_18518579827066659_8671000027546985535_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=VRyEzeKRkasQ7kNvwHgMjEk&amp;_nc_oc=AdmFLAnwshiD-HhRT7lJ5h8ISbKJxwhdIj4vn5dtUM0QozNsg7I-8ahsu0o6iaJpL_b3wj5ekTA2AoiU3Ds6FKdf&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrBLlZxG3hYz36s0rhW1l_dYVwYz4feiC1is4OhOMjaXg&amp;oe=696833C2&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/575997818_18518579827066659_8671000027546985535_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=VRyEzeKRkasQ7kNvwHgMjEk&amp;_nc_oc=AdmFLAnwshiD-HhRT7lJ5h8ISbKJxwhdIj4vn5dtUM0QozNsg7I-8ahsu0o6iaJpL_b3wj5ekTA2AoiU3Ds6FKdf&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrBLlZxG3hYz36s0rhW1l_dYVwYz4feiC1is4OhOMjaXg&amp;oe=696833C2&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/575997818_18518579827066659_8671000027546985535_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=VRyEzeKRkasQ7kNvwHgMjEk&amp;_nc_oc=AdmFLAnwshiD-HhRT7lJ5h8ISbKJxwhdIj4vn5dtUM0QozNsg7I-8ahsu0o6iaJpL_b3wj5ekTA2AoiU3Ds6FKdf&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrBLlZxG3hYz36s0rhW1l_dYVwYz4feiC1is4OhOMjaXg&amp;oe=696833C2&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/575997818_18518579827066659_8671000027546985535_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=100&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=VRyEzeKRkasQ7kNvwHgMjEk&amp;_nc_oc=AdmFLAnwshiD-HhRT7lJ5h8ISbKJxwhdIj4vn5dtUM0QozNsg7I-8ahsu0o6iaJpL_b3wj5ekTA2AoiU3Ds6FKdf&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfrBLlZxG3hYz36s0rhW1l_dYVwYz4feiC1is4OhOMjaXg&amp;oe=696833C2&quot;}\">\n            <span class=\"sbi-screenreader\">\u00a1 Llegaron nuestras super vacaciones recreativas!<\/span>\n            \t                    <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\u00a1 Llegaron nuestras super vacaciones recreativas! \n\u00a1Actividades emocionantes y seguras !\n\u00a1Cupos limitados! Inscr\u00edbete \ud83d\udcde 3203052651\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\" id=\"sbi_18102896026635687\" data-date=\"1761622277\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DQVRVHqDCSc\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-1.cdninstagram.com\/v\/t51.71878-15\/573184197_1246864700584290_6020300627173825049_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=102&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=ePU92eOTUKwQ7kNvwHawXXd&#038;_nc_oc=AdmtZbTt-AjjZf2k0_jdjz6atX_4KX88DiPR_USlpoGe_2NbpRLp4_XnnCEZXTyD2odiYDliedcNwGvxX2bCd0xQ&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_Afqxehhz_bhOnNnPG92Z1Q4jTCcGQew-u1ailAjexv735w&#038;oe=69684719\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/573184197_1246864700584290_6020300627173825049_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=ePU92eOTUKwQ7kNvwHawXXd&amp;_nc_oc=AdmtZbTt-AjjZf2k0_jdjz6atX_4KX88DiPR_USlpoGe_2NbpRLp4_XnnCEZXTyD2odiYDliedcNwGvxX2bCd0xQ&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afqxehhz_bhOnNnPG92Z1Q4jTCcGQew-u1ailAjexv735w&amp;oe=69684719&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/573184197_1246864700584290_6020300627173825049_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=ePU92eOTUKwQ7kNvwHawXXd&amp;_nc_oc=AdmtZbTt-AjjZf2k0_jdjz6atX_4KX88DiPR_USlpoGe_2NbpRLp4_XnnCEZXTyD2odiYDliedcNwGvxX2bCd0xQ&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afqxehhz_bhOnNnPG92Z1Q4jTCcGQew-u1ailAjexv735w&amp;oe=69684719&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/573184197_1246864700584290_6020300627173825049_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=ePU92eOTUKwQ7kNvwHawXXd&amp;_nc_oc=AdmtZbTt-AjjZf2k0_jdjz6atX_4KX88DiPR_USlpoGe_2NbpRLp4_XnnCEZXTyD2odiYDliedcNwGvxX2bCd0xQ&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afqxehhz_bhOnNnPG92Z1Q4jTCcGQew-u1ailAjexv735w&amp;oe=69684719&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.71878-15\\\/573184197_1246864700584290_6020300627173825049_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=ePU92eOTUKwQ7kNvwHawXXd&amp;_nc_oc=AdmtZbTt-AjjZf2k0_jdjz6atX_4KX88DiPR_USlpoGe_2NbpRLp4_XnnCEZXTyD2odiYDliedcNwGvxX2bCd0xQ&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afqxehhz_bhOnNnPG92Z1Q4jTCcGQew-u1ailAjexv735w&amp;oe=69684719&quot;}\">\n            <span class=\"sbi-screenreader\">Publicaci\u00f3n de Instagram 18102896026635687<\/span>\n            \t        <svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>            <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Publicaci\u00f3n de Instagram 18102896026635687\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_image sbi_new sbi_transition\" id=\"sbi_18086394496940227\" data-date=\"1761270109\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/p\/DQLIX7-jCdn\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-3.cdninstagram.com\/v\/t51.82787-15\/569402649_18515232481066659_1389009045581259668_n.webp?stp=dst-jpg_e35_tt6&#038;_nc_cat=108&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=vbImrgkNcv0Q7kNvwEhkPGP&#038;_nc_oc=AdlU4GdLLAxFBGV3G5ecVdBAqAFq7vsM8mmSMDaJbRVJAMoCGWi5j8WqDzb6sUlVB_n7EPD-XWC5vmKpe9rCx0Yj&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-3.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_Afp_ge_sicqhJfU_m6-O52aj95BpfkjvIjfGCTsldQbK1Q&#038;oe=696845B8\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569402649_18515232481066659_1389009045581259668_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=vbImrgkNcv0Q7kNvwEhkPGP&amp;_nc_oc=AdlU4GdLLAxFBGV3G5ecVdBAqAFq7vsM8mmSMDaJbRVJAMoCGWi5j8WqDzb6sUlVB_n7EPD-XWC5vmKpe9rCx0Yj&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afp_ge_sicqhJfU_m6-O52aj95BpfkjvIjfGCTsldQbK1Q&amp;oe=696845B8&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569402649_18515232481066659_1389009045581259668_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=vbImrgkNcv0Q7kNvwEhkPGP&amp;_nc_oc=AdlU4GdLLAxFBGV3G5ecVdBAqAFq7vsM8mmSMDaJbRVJAMoCGWi5j8WqDzb6sUlVB_n7EPD-XWC5vmKpe9rCx0Yj&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afp_ge_sicqhJfU_m6-O52aj95BpfkjvIjfGCTsldQbK1Q&amp;oe=696845B8&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569402649_18515232481066659_1389009045581259668_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=vbImrgkNcv0Q7kNvwEhkPGP&amp;_nc_oc=AdlU4GdLLAxFBGV3G5ecVdBAqAFq7vsM8mmSMDaJbRVJAMoCGWi5j8WqDzb6sUlVB_n7EPD-XWC5vmKpe9rCx0Yj&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afp_ge_sicqhJfU_m6-O52aj95BpfkjvIjfGCTsldQbK1Q&amp;oe=696845B8&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569402649_18515232481066659_1389009045581259668_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=108&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=vbImrgkNcv0Q7kNvwEhkPGP&amp;_nc_oc=AdlU4GdLLAxFBGV3G5ecVdBAqAFq7vsM8mmSMDaJbRVJAMoCGWi5j8WqDzb6sUlVB_n7EPD-XWC5vmKpe9rCx0Yj&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afp_ge_sicqhJfU_m6-O52aj95BpfkjvIjfGCTsldQbK1Q&amp;oe=696845B8&quot;}\">\n            <span class=\"sbi-screenreader\">Publicaci\u00f3n de Instagram 18086394496940227<\/span>\n            \t                    <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Publicaci\u00f3n de Instagram 18086394496940227\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_image sbi_new sbi_transition\" id=\"sbi_18085116050506244\" data-date=\"1761094741\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/p\/DQF54vUDGMr\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-1.cdninstagram.com\/v\/t51.82787-15\/569298706_18514805983066659_1044415424754938502_n.webp?stp=dst-jpg_e35_tt6&#038;_nc_cat=102&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=X6Y2VkvkmR8Q7kNvwE6L9eT&#038;_nc_oc=Adnh30ZPus8ROpgpbKCxPKKm0TolPTvOlRNt6LCBkkuy-ONBUdvdekGrHChClK7701j6An2HPqnUtcf-GLbFNHOw&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_Afr50u6RCjN-7ymaY7xx3zGCTF25e_ODYaBHkacCCRYNjw&#038;oe=696825D8\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569298706_18514805983066659_1044415424754938502_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=X6Y2VkvkmR8Q7kNvwE6L9eT&amp;_nc_oc=Adnh30ZPus8ROpgpbKCxPKKm0TolPTvOlRNt6LCBkkuy-ONBUdvdekGrHChClK7701j6An2HPqnUtcf-GLbFNHOw&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afr50u6RCjN-7ymaY7xx3zGCTF25e_ODYaBHkacCCRYNjw&amp;oe=696825D8&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569298706_18514805983066659_1044415424754938502_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=X6Y2VkvkmR8Q7kNvwE6L9eT&amp;_nc_oc=Adnh30ZPus8ROpgpbKCxPKKm0TolPTvOlRNt6LCBkkuy-ONBUdvdekGrHChClK7701j6An2HPqnUtcf-GLbFNHOw&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afr50u6RCjN-7ymaY7xx3zGCTF25e_ODYaBHkacCCRYNjw&amp;oe=696825D8&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569298706_18514805983066659_1044415424754938502_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=X6Y2VkvkmR8Q7kNvwE6L9eT&amp;_nc_oc=Adnh30ZPus8ROpgpbKCxPKKm0TolPTvOlRNt6LCBkkuy-ONBUdvdekGrHChClK7701j6An2HPqnUtcf-GLbFNHOw&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afr50u6RCjN-7ymaY7xx3zGCTF25e_ODYaBHkacCCRYNjw&amp;oe=696825D8&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/569298706_18514805983066659_1044415424754938502_n.webp?stp=dst-jpg_e35_tt6&amp;_nc_cat=102&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&amp;_nc_ohc=X6Y2VkvkmR8Q7kNvwE6L9eT&amp;_nc_oc=Adnh30ZPus8ROpgpbKCxPKKm0TolPTvOlRNt6LCBkkuy-ONBUdvdekGrHChClK7701j6An2HPqnUtcf-GLbFNHOw&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-1.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afr50u6RCjN-7ymaY7xx3zGCTF25e_ODYaBHkacCCRYNjw&amp;oe=696825D8&quot;}\">\n            <span class=\"sbi-screenreader\">La interacci\u00f3n con animales fortalece el desarrol<\/span>\n            \t                    <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"La interacci\u00f3n con animales fortalece el desarrollo de habilidades  sociales como la empat\u00eda, la responsabilidad, y la autoestima. \n\n! Te esperamos en Kiddo! \ud83d\udc15\ud83d\udc34\ud83d\udc07\ud83d\udc11\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\" id=\"sbi_18020478176583462\" data-date=\"1759488782\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DPWCuAijcRM\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-2.cdninstagram.com\/v\/t51.71878-15\/558904171_1139653844898678_6651802788433319784_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=107&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=9BrgosvxLM4Q7kNvwFQy3VI&#038;_nc_oc=AdksASQ_i4sZsup05k5urUBX69bol1ZKZOSlskeUz7Rv1EEcGWqcPRpJvyI-TeFh3Okm4beXVL0eF4PhszKRctKi&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_AfolGQo-SkUANqhX6NPj-gib91yXqZfL-ojavjXVqaED1Q&#038;oe=69685A91\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/558904171_1139653844898678_6651802788433319784_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=107&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=9BrgosvxLM4Q7kNvwFQy3VI&amp;_nc_oc=AdksASQ_i4sZsup05k5urUBX69bol1ZKZOSlskeUz7Rv1EEcGWqcPRpJvyI-TeFh3Okm4beXVL0eF4PhszKRctKi&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfolGQo-SkUANqhX6NPj-gib91yXqZfL-ojavjXVqaED1Q&amp;oe=69685A91&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/558904171_1139653844898678_6651802788433319784_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=107&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=9BrgosvxLM4Q7kNvwFQy3VI&amp;_nc_oc=AdksASQ_i4sZsup05k5urUBX69bol1ZKZOSlskeUz7Rv1EEcGWqcPRpJvyI-TeFh3Okm4beXVL0eF4PhszKRctKi&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfolGQo-SkUANqhX6NPj-gib91yXqZfL-ojavjXVqaED1Q&amp;oe=69685A91&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/558904171_1139653844898678_6651802788433319784_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=107&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=9BrgosvxLM4Q7kNvwFQy3VI&amp;_nc_oc=AdksASQ_i4sZsup05k5urUBX69bol1ZKZOSlskeUz7Rv1EEcGWqcPRpJvyI-TeFh3Okm4beXVL0eF4PhszKRctKi&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfolGQo-SkUANqhX6NPj-gib91yXqZfL-ojavjXVqaED1Q&amp;oe=69685A91&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-2.cdninstagram.com\\\/v\\\/t51.71878-15\\\/558904171_1139653844898678_6651802788433319784_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=107&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=9BrgosvxLM4Q7kNvwFQy3VI&amp;_nc_oc=AdksASQ_i4sZsup05k5urUBX69bol1ZKZOSlskeUz7Rv1EEcGWqcPRpJvyI-TeFh3Okm4beXVL0eF4PhszKRctKi&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-2.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_AfolGQo-SkUANqhX6NPj-gib91yXqZfL-ojavjXVqaED1Q&amp;oe=69685A91&quot;}\">\n            <span class=\"sbi-screenreader\">Publicaci\u00f3n de Instagram 18020478176583462<\/span>\n            \t        <svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>            <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Publicaci\u00f3n de Instagram 18020478176583462\">\n        <\/a>\n    <\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\" id=\"sbi_17987283296676630\" data-date=\"1749577557\">\n    <div class=\"sbi_photo_wrap\">\n        <a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DKup90Tpp-M\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-lga3-3.cdninstagram.com\/v\/t51.71878-15\/504208128_1185520929929999_5331317757330440271_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=106&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=8Y9ERD7r0lUQ7kNvwENhCJS&#038;_nc_oc=AdnbBv_NqqxwwxWRyJzPrO1FpWJrXrR0MwqIGeXY50OJLcbovVU7ZjROnePlZh_OpWHXn2WdP74iBm4Z6A62d2ml&#038;_nc_zt=23&#038;_nc_ht=scontent-lga3-3.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&#038;oh=00_Afo8rJgNTLxd5vJBhalQQr2ih7KrO9Ls0e1LJMcZSMnI3w&#038;oe=69683BBF\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/504208128_1185520929929999_5331317757330440271_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=8Y9ERD7r0lUQ7kNvwENhCJS&amp;_nc_oc=AdnbBv_NqqxwwxWRyJzPrO1FpWJrXrR0MwqIGeXY50OJLcbovVU7ZjROnePlZh_OpWHXn2WdP74iBm4Z6A62d2ml&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afo8rJgNTLxd5vJBhalQQr2ih7KrO9Ls0e1LJMcZSMnI3w&amp;oe=69683BBF&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/504208128_1185520929929999_5331317757330440271_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=8Y9ERD7r0lUQ7kNvwENhCJS&amp;_nc_oc=AdnbBv_NqqxwwxWRyJzPrO1FpWJrXrR0MwqIGeXY50OJLcbovVU7ZjROnePlZh_OpWHXn2WdP74iBm4Z6A62d2ml&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afo8rJgNTLxd5vJBhalQQr2ih7KrO9Ls0e1LJMcZSMnI3w&amp;oe=69683BBF&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/504208128_1185520929929999_5331317757330440271_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=8Y9ERD7r0lUQ7kNvwENhCJS&amp;_nc_oc=AdnbBv_NqqxwwxWRyJzPrO1FpWJrXrR0MwqIGeXY50OJLcbovVU7ZjROnePlZh_OpWHXn2WdP74iBm4Z6A62d2ml&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afo8rJgNTLxd5vJBhalQQr2ih7KrO9Ls0e1LJMcZSMnI3w&amp;oe=69683BBF&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-lga3-3.cdninstagram.com\\\/v\\\/t51.71878-15\\\/504208128_1185520929929999_5331317757330440271_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=8Y9ERD7r0lUQ7kNvwENhCJS&amp;_nc_oc=AdnbBv_NqqxwwxWRyJzPrO1FpWJrXrR0MwqIGeXY50OJLcbovVU7ZjROnePlZh_OpWHXn2WdP74iBm4Z6A62d2ml&amp;_nc_zt=23&amp;_nc_ht=scontent-lga3-3.cdninstagram.com&amp;edm=ANo9K5cEAAAA&amp;_nc_gid=MtuPOwyAd3aH0Ayjawhr_A&amp;oh=00_Afo8rJgNTLxd5vJBhalQQr2ih7KrO9Ls0e1LJMcZSMnI3w&amp;oe=69683BBF&quot;}\">\n            <span class=\"sbi-screenreader\">Celebraci\u00f3n D\u00eda del estudiante kiddo \ud83c\udf08Un d\u00eda<\/span>\n            \t        <svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>            <img decoding=\"async\" src=\"https:\/\/mikiddo.com.co\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Celebraci\u00f3n D\u00eda del estudiante kiddo \ud83c\udf08Un d\u00eda lleno de aventura y diversi\u00f3n \ud83e\udd73\">\n        <\/a>\n    <\/div>\n<\/div>    <\/div>\n\n\t<div id=\"sbi_load\" >\n\n\t\n\t\t\t<span class=\"sbi_follow_btn sbi_custom\">\n        <a href=\"https:\/\/www.instagram.com\/mikiddo.com.co\/\" style=\"background: rgb(64,139,209);\" target=\"_blank\" rel=\"nofollow noopener\">\n            <svg class=\"svg-inline--fa fa-instagram fa-w-14\" aria-hidden=\"true\" data-fa-processed=\"\" aria-label=\"Instagram\" data-prefix=\"fab\" data-icon=\"instagram\" role=\"img\" viewBox=\"0 0 448 512\">\n\t                <path fill=\"currentColor\" d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path>\n\t            <\/svg>            <span>Seguir en Instagram<\/span>\n        <\/a>\n    <\/span>\n\t\n<\/div>\n\n\t    <span class=\"sbi_resized_image_data\" data-feed-id=\"*1\" data-resized=\"{&quot;17987283296676630&quot;:{&quot;id&quot;:&quot;504208128_1185520929929999_5331317757330440271_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18020478176583462&quot;:{&quot;id&quot;:&quot;558904171_1139653844898678_6651802788433319784_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18085116050506244&quot;:{&quot;id&quot;:&quot;569298706_18514805983066659_1044415424754938502_n&quot;,&quot;ratio&quot;:&quot;1.00&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18086394496940227&quot;:{&quot;id&quot;:&quot;569402649_18515232481066659_1389009045581259668_n&quot;,&quot;ratio&quot;:&quot;0.75&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18102896026635687&quot;:{&quot;id&quot;:&quot;573184197_1246864700584290_6020300627173825049_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18106493620624839&quot;:{&quot;id&quot;:&quot;575997818_18518579827066659_8671000027546985535_n&quot;,&quot;ratio&quot;:&quot;0.75&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18313519198216554&quot;:{&quot;id&quot;:&quot;582236157_1632961561445462_7778157218133196609_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18076733042324563&quot;:{&quot;id&quot;:&quot;581007704_18520884226066659_4907566387772387064_n&quot;,&quot;ratio&quot;:&quot;0.80&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18085095811832845&quot;:{&quot;id&quot;:&quot;587490330_2421005255002940_8181823124154054745_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;}}\">\n\t<\/span>\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab740c6 e-flex e-con-boxed e-con e-parent\" data-id=\"ab740c6\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6554cda e-con-full e-flex e-con e-child\" data-id=\"6554cda\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5795f22 e-con-full e-flex e-con e-child\" data-id=\"5795f22\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5a1fb03 e-flex e-con-boxed e-con e-child\" data-id=\"5a1fb03\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-718cdf9 elementor-widget elementor-widget-text-editor\" data-id=\"718cdf9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 13-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Conoce aqui el manual de convivencia.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a39983 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1a39983\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mikiddo.com.co\/kiddo2025\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Haz clic aqu\u00ed<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dba6ed e-flex e-con-boxed e-con e-child\" data-id=\"6dba6ed\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcc1b0d e-con-full e-flex e-con e-child\" data-id=\"dcc1b0d\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Centro Educativo Infantil Kiddo \u00a1Donde el aprendizaje es una aventura! \u00a1Bienvenidos a nuestro colegio, donde la magia y la aventura nunca terminan! Descrube M\u00e1s \u00bfPor que elegirnos? Nuestros valores fundamentales. Porque le apostamos por una educaci\u00f3n basada en la ciencia, que comprende c\u00f3mo aprende el cerebro infantil y c\u00f3mo las emociones, el entorno y las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages\/45"}],"collection":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":345,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages\/45\/revisions"}],"predecessor-version":[{"id":5180,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages\/45\/revisions\/5180"}],"wp:attachment":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}