{"id":4716,"date":"2024-06-21T19:13:12","date_gmt":"2024-06-22T00:13:12","guid":{"rendered":"https:\/\/mikiddo.com.co\/index.php\/register\/"},"modified":"2025-06-28T00:05:57","modified_gmt":"2025-06-28T05:05:57","slug":"register","status":"publish","type":"page","link":"https:\/\/mikiddo.com.co\/index.php\/register\/","title":{"rendered":"Registro"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4716\" class=\"elementor elementor-4716\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19d7e24e e-flex e-con-boxed e-con e-parent\" data-id=\"19d7e24e\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24b09858 elementor-widget elementor-widget-shortcode\" data-id=\"24b09858\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"um um-register um-4710\">\n\t<div class=\"um-form\" data-mode=\"register\">\n\t\t<form method=\"post\" action=\"\">\n\t\t\t<div class=\"um-row _um_row_1 \" style=\"margin: 0 0 30px 0;\"><div class=\"um-col-1\"><div  id=\"um_field_4710_user_login\" class=\"um-field um-field-text  um-field-user_login um-field-text um-field-type_text\" data-key=\"user_login\"><div class=\"um-field-label\"><label for=\"user_login-4710\">Nombre de usuario<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid \" type=\"text\" name=\"user_login-4710\" id=\"user_login-4710\" value=\"\" placeholder=\"\" data-validate=\"unique_username\" data-key=\"user_login\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_4710_first_name\" class=\"um-field um-field-text  um-field-first_name um-field-text um-field-type_text\" data-key=\"first_name\"><div class=\"um-field-label\"><label for=\"first_name-4710\">Nombre<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid \" type=\"text\" name=\"first_name-4710\" id=\"first_name-4710\" value=\"\" placeholder=\"\" data-validate=\"\" data-key=\"first_name\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_4710_last_name\" class=\"um-field um-field-text  um-field-last_name um-field-text um-field-type_text\" data-key=\"last_name\"><div class=\"um-field-label\"><label for=\"last_name-4710\">Apellidos<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid \" type=\"text\" name=\"last_name-4710\" id=\"last_name-4710\" value=\"\" placeholder=\"\" data-validate=\"\" data-key=\"last_name\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_4710_user_email\" class=\"um-field um-field-text  um-field-user_email um-field-text um-field-type_text\" data-key=\"user_email\"><div class=\"um-field-label\"><label for=\"user_email-4710\">Direcci\u00f3n de correo electr\u00f3nico<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid \" type=\"text\" name=\"user_email-4710\" id=\"user_email-4710\" value=\"\" placeholder=\"\" data-validate=\"unique_email\" data-key=\"user_email\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_4710_user_password\" class=\"um-field um-field-password  um-field-user_password um-field-password um-field-type_password\" data-key=\"user_password\"><div class=\"um-field-label\"><label for=\"user_password-4710\">Contrase\u00f1a<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><div class=\"um-field-area-password\">\n\t\t\t\t\t\t\t\t\t<input class=\"um-form-field valid \" type=\"password\" name=\"user_password-4710\" id=\"user_password-4710\" value=\"\" placeholder=\"\" data-validate=\"\" data-key=\"user_password\"  aria-invalid=\"false\" \/>\n\t\t\t\t\t\t\t\t\t<span class=\"um-toggle-password\"><i class=\"um-icon-eye\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_4710_confirm_user_password\" class=\"um-field um-field-password  um-field-user_password um-field-password um-field-type_password\" data-key=\"confirm_user_password\"><div class=\"um-field-label\"><label for=\"confirm_user_password-4710\">Confirmar Contrase\u00f1a<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><div class=\"um-field-area-password\"><input class=\"um-form-field valid \" type=\"password\" name=\"confirm_user_password-4710\" id=\"confirm_user_password-4710\" value=\"\" placeholder=\"Confirmar Contrase\u00f1a\" data-validate=\"\" data-key=\"confirm_user_password\"  aria-invalid=\"false\" \/><span class=\"um-toggle-password\"><i class=\"um-icon-eye\"><\/i><\/span><\/div><\/div><\/div><\/div><\/div>\t\t<input type=\"hidden\" name=\"form_id\" id=\"form_id_4710\" value=\"4710\" \/>\n\t\n\t<p class=\"um_request_name\">\n\t\t<label for=\"um_request_4710\">Only fill in if you are not human<\/label>\n\t\t<input type=\"hidden\" name=\"um_request\" id=\"um_request_4710\" class=\"input\" value=\"\" size=\"25\" autocomplete=\"off\" \/>\n\t<\/p>\n\n\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"9bcf64dcea\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/4716\" \/>\n\t<div class=\"um-col-alt\">\n\n\t\t\n\t\t\t<div class=\"um-left um-half\">\n\t\t\t\t<input type=\"submit\" value=\"Registro\" class=\"um-button\" id=\"um-submit-btn\" \/>\n\t\t\t<\/div>\n\t\t\t<div class=\"um-right um-half\">\n\t\t\t\t<a href=\"https:\/\/mikiddo.com.co\/index.php\/login\/\" class=\"um-button um-alt\">\n\t\t\t\t\tAcceder\t\t\t\t<\/a>\n\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"um-clear\"><\/div>\n\n\t<\/div>\n\n\t\t\t<\/form>\n\t<\/div>\n<\/div>\n<style>\n\t\t\t.um-4710.um {\n\t\t\tmax-width: 450px;\n\t\t}\n\t\t<\/style>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages\/4716"}],"collection":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=4716"}],"version-history":[{"count":3,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages\/4716\/revisions"}],"predecessor-version":[{"id":5086,"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/pages\/4716\/revisions\/5086"}],"wp:attachment":[{"href":"https:\/\/mikiddo.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=4716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}